{"id":42562,"date":"2024-10-03T18:20:16","date_gmt":"2024-10-03T18:20:16","guid":{"rendered":"https:\/\/redeportivamx.com\/?p=42562"},"modified":"2024-10-03T18:20:18","modified_gmt":"2024-10-03T18:20:18","slug":"alonso-y-anselmi-a-arabia","status":"publish","type":"post","link":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/","title":{"rendered":"\u00bfAlonso y Anselmi a Arabia?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El cambio de Cruz Azul del 2023 al 2024 fue de 180 grados, todo gracias a la labor de Iv\u00e1n Alonso y Martin Anselmi en el club <em>cementero<\/em>, situaci\u00f3n que ya los han puesto en la miradas de otros equipos, entre ellos algunos de Arabia Saudita, los cuales tendr\u00edan en sus planes hacerse con sus servicios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con Matteo Moretto, periodista especializado en fichajes para Relevo, el trabajo de Alonso y Anselmi ha comenzado a llamar la atenci\u00f3n del otro lado del charco, siendo algunos clubes importantes de Arabia Saudita los que los que los contemplan \u201cpara liderar su proyecto a corto plazo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este no es el primer rumor de salida que ha rodeado a estas figuras, ya que en meses anteriores se especul\u00f3 sobre el inter\u00e9s de la Selecci\u00f3n de Ecuador sobre Martin Anselmi, situaci\u00f3n que no progreso, a pesar de que el estratega contaba con una cl\u00e1usula especial en cuanto a combinados nacionales se refiere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe mencionar que la intenci\u00f3n de Cruz Azul es mantener a ambos, esto gracias al gran trabajo que han logrado en el torneo y medio en M\u00e9xico, de hecho, el timonel argentino fue renovado hasta 2027 justo antes de enfrentar a los Pumas en los Cuartos de Final del Clausura 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente la <em>M\u00e1quina <\/em>se presenta como l\u00edder del Apertura 2024 despu\u00e9s de 10 jornadas, adem\u00e1s de ser el principal candidato a llevarse el campeonato al final de la campa\u00f1a, aunque para eso tendr\u00e1 que mantener su posici\u00f3n en las siete jornadas restantes y el resto de la liguilla.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"785\" height=\"1024\" src=\"http:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-12-785x1024.png\" alt=\"\" class=\"wp-image-42563\" srcset=\"https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-12-785x1024.png 785w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-12-230x300.png 230w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-12-768x1001.png 768w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-12.png 1080w\" sizes=\"(max-width: 785px) 100vw, 785px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cambio de Cruz Azul del 2023 al 2024 fue de 180 grados, todo gracias a la labor de Iv\u00e1n Alonso y Martin Anselmi en el club cementero, situaci\u00f3n que ya los han puesto en la miradas de otros equipos, entre ellos algunos de Arabia Saudita, los cuales tendr\u00edan en sus planes hacerse con sus [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":42564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[132,975,885],"class_list":["post-42562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-liga-bbva-mx","tag-cruz-azul","tag-ivan-alonso","tag-martin-anselmi"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El cambio de Cruz Azul del 2023 al 2024 fue de 180 grados, todo gracias a la labor de Iv\u00e1n Alonso y Martin Anselmi en el club cementero, situaci\u00f3n que ya los han puesto en la miradas de otros equipos, entre ellos algunos de Arabia Saudita, los cuales tendr\u00edan en sus planes hacerse con sus\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Miguel \u00c1ngel Bustamante Rosas\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Redeportiva MX - \u00a1Conectando tu pasi\u00f3n!\" \/>\n\t\t<meta property=\"og:type\" content=\"sport\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfAlonso y Anselmi a Arabia? - Redeportiva MX\" \/>\n\t\t<meta property=\"og:description\" content=\"El cambio de Cruz Azul del 2023 al 2024 fue de 180 grados, todo gracias a la labor de Iv\u00e1n Alonso y Martin Anselmi en el club cementero, situaci\u00f3n que ya los han puesto en la miradas de otros equipos, entre ellos algunos de Arabia Saudita, los cuales tendr\u00edan en sus planes hacerse con sus\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-13.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-13.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"717\" \/>\n\t\t<meta property=\"og:image:height\" content=\"402\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@Redeportivamx\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfAlonso y Anselmi a Arabia? - Redeportiva MX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El cambio de Cruz Azul del 2023 al 2024 fue de 180 grados, todo gracias a la labor de Iv\u00e1n Alonso y Martin Anselmi en el club cementero, situaci\u00f3n que ya los han puesto en la miradas de otros equipos, entre ellos algunos de Arabia Saudita, los cuales tendr\u00edan en sus planes hacerse con sus\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@Redeportivamx\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-13.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#blogposting\",\"name\":\"\\u00bfAlonso y Anselmi a Arabia? - Redeportiva MX\",\"headline\":\"\\u00bfAlonso y Anselmi a Arabia?\",\"author\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/miguel-angel-bustamante-rosas\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/image-13.png\",\"width\":717,\"height\":402},\"datePublished\":\"2024-10-03T18:20:16-06:00\",\"dateModified\":\"2024-10-03T18:20:18-06:00\",\"inLanguage\":\"es-MX\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#webpage\"},\"articleSection\":\"Liga BBVA MX, Cruz Azul, Iv\\u00e1n Alonso, Mart\\u00edn Anselmi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/redeportivamx.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/liga-bbva-mx\\\/#listItem\",\"name\":\"Liga BBVA MX\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/liga-bbva-mx\\\/#listItem\",\"position\":2,\"name\":\"Liga BBVA MX\",\"item\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/liga-bbva-mx\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#listItem\",\"name\":\"\\u00bfAlonso y Anselmi a Arabia?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfAlonso y Anselmi a Arabia?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/liga-bbva-mx\\\/#listItem\",\"name\":\"Liga BBVA MX\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\",\"name\":\"redeportivamx.com\",\"description\":\"\\u00a1Conectando tu pasi\\u00f3n!\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61565592572733\",\"https:\\\/\\\/x.com\\\/Redeportivamx?s=20\",\"https:\\\/\\\/www.instagram.com\\\/redeportivamx\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@redeportiva.mx\",\"https:\\\/\\\/www.youtube.com\\\/@Redeportiva-MX\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/miguel-angel-bustamante-rosas\\\/#author\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/miguel-angel-bustamante-rosas\\\/\",\"name\":\"Miguel \\u00c1ngel Bustamante Rosas\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33d4d1eb2fbf049470fcc1828f04678c4d08c13b2be7e4f36356396ddc750484?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Miguel \\u00c1ngel Bustamante Rosas\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#webpage\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/\",\"name\":\"\\u00bfAlonso y Anselmi a Arabia? - Redeportiva MX\",\"description\":\"El cambio de Cruz Azul del 2023 al 2024 fue de 180 grados, todo gracias a la labor de Iv\\u00e1n Alonso y Martin Anselmi en el club cementero, situaci\\u00f3n que ya los han puesto en la miradas de otros equipos, entre ellos algunos de Arabia Saudita, los cuales tendr\\u00edan en sus planes hacerse con sus\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/miguel-angel-bustamante-rosas\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/miguel-angel-bustamante-rosas\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/image-13.png\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#mainImage\",\"width\":717,\"height\":402},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2024\\\/10\\\/03\\\/alonso-y-anselmi-a-arabia\\\/#mainImage\"},\"datePublished\":\"2024-10-03T18:20:16-06:00\",\"dateModified\":\"2024-10-03T18:20:18-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#website\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/\",\"name\":\"redeportivamx.com\",\"description\":\"\\u00a1Conectando tu pasi\\u00f3n!\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfAlonso y Anselmi a Arabia? - Redeportiva MX","description":"El cambio de Cruz Azul del 2023 al 2024 fue de 180 grados, todo gracias a la labor de Iv\u00e1n Alonso y Martin Anselmi en el club cementero, situaci\u00f3n que ya los han puesto en la miradas de otros equipos, entre ellos algunos de Arabia Saudita, los cuales tendr\u00edan en sus planes hacerse con sus","canonical_url":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#blogposting","name":"\u00bfAlonso y Anselmi a Arabia? - Redeportiva MX","headline":"\u00bfAlonso y Anselmi a Arabia?","author":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/miguel-angel-bustamante-rosas\/#author"},"publisher":{"@id":"https:\/\/redeportivamx.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-13.png","width":717,"height":402},"datePublished":"2024-10-03T18:20:16-06:00","dateModified":"2024-10-03T18:20:18-06:00","inLanguage":"es-MX","mainEntityOfPage":{"@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#webpage"},"isPartOf":{"@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#webpage"},"articleSection":"Liga BBVA MX, Cruz Azul, Iv\u00e1n Alonso, Mart\u00edn Anselmi"},{"@type":"BreadcrumbList","@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/redeportivamx.com#listItem","position":1,"name":"Home","item":"https:\/\/redeportivamx.com","nextItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/#listItem","name":"Liga BBVA MX"}},{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/#listItem","position":2,"name":"Liga BBVA MX","item":"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/","nextItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#listItem","name":"\u00bfAlonso y Anselmi a Arabia?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#listItem","position":3,"name":"\u00bfAlonso y Anselmi a Arabia?","previousItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/#listItem","name":"Liga BBVA MX"}}]},{"@type":"Organization","@id":"https:\/\/redeportivamx.com\/#organization","name":"redeportivamx.com","description":"\u00a1Conectando tu pasi\u00f3n!","url":"https:\/\/redeportivamx.com\/","sameAs":["https:\/\/www.facebook.com\/profile.php?id=61565592572733","https:\/\/x.com\/Redeportivamx?s=20","https:\/\/www.instagram.com\/redeportivamx\/","https:\/\/www.tiktok.com\/@redeportiva.mx","https:\/\/www.youtube.com\/@Redeportiva-MX"]},{"@type":"Person","@id":"https:\/\/redeportivamx.com\/index.php\/author\/miguel-angel-bustamante-rosas\/#author","url":"https:\/\/redeportivamx.com\/index.php\/author\/miguel-angel-bustamante-rosas\/","name":"Miguel \u00c1ngel Bustamante Rosas","image":{"@type":"ImageObject","@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/33d4d1eb2fbf049470fcc1828f04678c4d08c13b2be7e4f36356396ddc750484?s=96&d=mm&r=g","width":96,"height":96,"caption":"Miguel \u00c1ngel Bustamante Rosas"}},{"@type":"WebPage","@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#webpage","url":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/","name":"\u00bfAlonso y Anselmi a Arabia? - Redeportiva MX","description":"El cambio de Cruz Azul del 2023 al 2024 fue de 180 grados, todo gracias a la labor de Iv\u00e1n Alonso y Martin Anselmi en el club cementero, situaci\u00f3n que ya los han puesto en la miradas de otros equipos, entre ellos algunos de Arabia Saudita, los cuales tendr\u00edan en sus planes hacerse con sus","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/redeportivamx.com\/#website"},"breadcrumb":{"@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#breadcrumblist"},"author":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/miguel-angel-bustamante-rosas\/#author"},"creator":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/miguel-angel-bustamante-rosas\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-13.png","@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#mainImage","width":717,"height":402},"primaryImageOfPage":{"@id":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/#mainImage"},"datePublished":"2024-10-03T18:20:16-06:00","dateModified":"2024-10-03T18:20:18-06:00"},{"@type":"WebSite","@id":"https:\/\/redeportivamx.com\/#website","url":"https:\/\/redeportivamx.com\/","name":"redeportivamx.com","description":"\u00a1Conectando tu pasi\u00f3n!","inLanguage":"es-MX","publisher":{"@id":"https:\/\/redeportivamx.com\/#organization"}}]},"og:locale":"es_MX","og:site_name":"Redeportiva MX - \u00a1Conectando tu pasi\u00f3n!","og:type":"sport","og:title":"\u00bfAlonso y Anselmi a Arabia? - Redeportiva MX","og:description":"El cambio de Cruz Azul del 2023 al 2024 fue de 180 grados, todo gracias a la labor de Iv\u00e1n Alonso y Martin Anselmi en el club cementero, situaci\u00f3n que ya los han puesto en la miradas de otros equipos, entre ellos algunos de Arabia Saudita, los cuales tendr\u00edan en sus planes hacerse con sus","og:url":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/","og:image":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-13.png","og:image:secure_url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-13.png","og:image:width":717,"og:image:height":402,"twitter:card":"summary_large_image","twitter:site":"@Redeportivamx","twitter:title":"\u00bfAlonso y Anselmi a Arabia? - Redeportiva MX","twitter:description":"El cambio de Cruz Azul del 2023 al 2024 fue de 180 grados, todo gracias a la labor de Iv\u00e1n Alonso y Martin Anselmi en el club cementero, situaci\u00f3n que ya los han puesto en la miradas de otros equipos, entre ellos algunos de Arabia Saudita, los cuales tendr\u00edan en sus planes hacerse con sus","twitter:creator":"@Redeportivamx","twitter:image":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-13.png"},"aioseo_meta_data":{"post_id":"42562","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-10-03 18:20:18","updated":"2025-06-04 19:23:08","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/redeportivamx.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/\" title=\"Liga BBVA MX\">Liga BBVA MX<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfAlonso y Anselmi a Arabia?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/redeportivamx.com"},{"label":"Liga BBVA MX","link":"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/"},{"label":"\u00bfAlonso y Anselmi a Arabia?","link":"https:\/\/redeportivamx.com\/index.php\/2024\/10\/03\/alonso-y-anselmi-a-arabia\/"}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2024\/10\/image-13.png","_links":{"self":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/42562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/comments?post=42562"}],"version-history":[{"count":1,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/42562\/revisions"}],"predecessor-version":[{"id":42566,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/42562\/revisions\/42566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/media\/42564"}],"wp:attachment":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/media?parent=42562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/categories?post=42562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/tags?post=42562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}