{"id":31812,"date":"2023-11-27T03:13:57","date_gmt":"2023-11-27T03:13:57","guid":{"rendered":"https:\/\/redeportivamx.com\/?p=31812"},"modified":"2023-11-27T03:27:12","modified_gmt":"2023-11-27T03:27:12","slug":"el-world-padel-tour-mexico-ya-tiene-a-sus-campeones","status":"publish","type":"post","link":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/","title":{"rendered":"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Concluy\u00f3 el M\u00e9xico Open 1000, celebrado en el Gimnasio Ol\u00edmpico Juan de la Barrera y ya conocemos a los ganadores del torneo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se celebraron los partidos finales del WPT M\u00e9xico 1000, partidos con los que concluy\u00f3 tambi\u00e9n el evento. Bea Gonz\u00e1lez y Delfina Brea vencieron a Tamara Icardo y Virginia Riera en dos sets con 6-4 y 6-2 en el marcador. Aunque al principio Tamara y Virginia presentaron buen juego y respondieron de manera adecuada a los saques de sus rivales, el juego se les fue de las manos poco a poco. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el segundo set Bea y Brea lograron generar errores en sus contrincantes, tanto en golpe\u00f3 como en fuerza por lo que sin mayor inconveniente lograron el Campeonato.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Match Point con el que <a href=\"https:\/\/twitter.com\/beaglez_padel?ref_src=twsrc%5Etfw\">@beaglez_padel<\/a> y <a href=\"https:\/\/twitter.com\/DelfiBrea?ref_src=twsrc%5Etfw\">@DelfiBrea<\/a> obtuvieron el campeonato en el <a href=\"https:\/\/twitter.com\/hashtag\/WPTM%C3%A9xicoOpen?src=hash&amp;ref_src=twsrc%5Etfw\">#WPTM\u00e9xicoOpen<\/a> <a href=\"https:\/\/t.co\/fb4pEa1Ly2\">pic.twitter.com\/fb4pEa1Ly2<\/a><\/p>&mdash; Ivan Araujo (@IvAraujo7) <a href=\"https:\/\/twitter.com\/IvAraujo7\/status\/1728977579334578642?ref_src=twsrc%5Etfw\">November 27, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Agust\u00edn Tapia y Arturo Coello lograron derrotar a Leo Augsburger y Tino Libaak 6-4 y 6-2 tambi\u00e9n en dos sets. El partido comenz\u00f3 bastante parejo con Libaak y Augsburger tomando la ventaja, pero tras ir empatados 4-4, Coello y Tapia comenzaron con remates potentes y lograron llevarse el set.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el segundo set, el dominio de los n\u00famero 1 del mundo fue a\u00fan mayor, pues no bajaron la intensidad y respond\u00edan con disparos certeros que terminaban fuera de la cancha. Sus saques, la fuerza al golpear, la coordinaci\u00f3n y comunicaci\u00f3n hicieron que Agust\u00edn y Arturo se llevar\u00e1n el Campeonato a casa y denostraran por qu\u00e9 son los n\u00famero uno.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Match Point con el que <a href=\"https:\/\/twitter.com\/agustapiacarp?ref_src=twsrc%5Etfw\">@agustapiacarp<\/a> y <a href=\"https:\/\/twitter.com\/Arturocoello__?ref_src=twsrc%5Etfw\">@Arturocoello__<\/a> sellaron el campeonato en el <a href=\"https:\/\/twitter.com\/hashtag\/WPTM%C3%A9xicoOpen?src=hash&amp;ref_src=twsrc%5Etfw\">#WPTM\u00e9xicoOpen<\/a>. Confirmando por qu\u00e9 son los n\u00famero 1 del mundo!<a href=\"https:\/\/twitter.com\/hashtag\/Padel?src=hash&amp;ref_src=twsrc%5Etfw\">#Padel<\/a> <a href=\"https:\/\/t.co\/n22uZIrpD2\">pic.twitter.com\/n22uZIrpD2<\/a><\/p>&mdash; Ivan Araujo (@IvAraujo7) <a href=\"https:\/\/twitter.com\/IvAraujo7\/status\/1728978252868600135?ref_src=twsrc%5Etfw\">November 27, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El siguiente evento se celebrar\u00e1 en Barcelona, ser\u00e1 el Torneo Master Final donde se enfrentar\u00e1n los equipos con mejor posici\u00f3n en el ranking para definir a los Campeones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concluy\u00f3 el M\u00e9xico Open 1000, celebrado en el Gimnasio Ol\u00edmpico Juan de la Barrera y ya conocemos a los ganadores del torneo. Se celebraron los partidos finales del WPT M\u00e9xico 1000, partidos con los que concluy\u00f3 tambi\u00e9n el evento. Bea Gonz\u00e1lez y Delfina Brea vencieron a Tamara Icardo y Virginia Riera en dos sets con [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":31816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[633,632,552,553],"class_list":["post-31812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros-deportes","tag-agustin-tapia","tag-arturo-coello","tag-padel","tag-world-padel-tour"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Concluy\u00f3 el M\u00e9xico Open 1000, celebrado en el Gimnasio Ol\u00edmpico Juan de la Barrera y ya conocemos a los ganadores del torneo. Se celebraron los partidos finales del WPT M\u00e9xico 1000, partidos con los que concluy\u00f3 tambi\u00e9n el evento. Bea Gonz\u00e1lez y Delfina Brea vencieron a Tamara Icardo y Virginia Riera en dos sets con\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ivan Emeterio Araujo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Redeportiva MX - \u00a1Conectando tu pasi\u00f3n!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones! - Redeportiva MX\" \/>\n\t\t<meta property=\"og:description\" content=\"Concluy\u00f3 el M\u00e9xico Open 1000, celebrado en el Gimnasio Ol\u00edmpico Juan de la Barrera y ya conocemos a los ganadores del torneo. Se celebraron los partidos finales del WPT M\u00e9xico 1000, partidos con los que concluy\u00f3 tambi\u00e9n el evento. Bea Gonz\u00e1lez y Delfina Brea vencieron a Tamara Icardo y Virginia Riera en dos sets con\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-11-27T03:13:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-11-27T03:27:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones! - Redeportiva MX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Concluy\u00f3 el M\u00e9xico Open 1000, celebrado en el Gimnasio Ol\u00edmpico Juan de la Barrera y ya conocemos a los ganadores del torneo. Se celebraron los partidos finales del WPT M\u00e9xico 1000, partidos con los que concluy\u00f3 tambi\u00e9n el evento. Bea Gonz\u00e1lez y Delfina Brea vencieron a Tamara Icardo y Virginia Riera en dos sets con\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#blogposting\",\"name\":\"\\u00a1El World Padel Tour M\\u00e9xico ya tiene a sus campeones! - Redeportiva MX\",\"headline\":\"\\u00a1El World Padel Tour M\\u00e9xico ya tiene a sus campeones!\",\"author\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Screenshot_20231126_211156_Instagram-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Foto: Instagram @wptmexico\"},\"datePublished\":\"2023-11-27T03:13:57+00:00\",\"dateModified\":\"2023-11-27T03:27:12+00:00\",\"inLanguage\":\"es-MX\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#webpage\"},\"articleSection\":\"Otros Deportes, Agust\\u00edn Tapia, Arturo Coello, Padel, World Padel Tour\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/redeportivamx.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/otros-deportes\\\/#listItem\",\"name\":\"Otros Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/otros-deportes\\\/#listItem\",\"position\":2,\"name\":\"Otros Deportes\",\"item\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/otros-deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#listItem\",\"name\":\"\\u00a1El World Padel Tour M\\u00e9xico ya tiene a sus campeones!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#listItem\",\"position\":3,\"name\":\"\\u00a1El World Padel Tour M\\u00e9xico ya tiene a sus campeones!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/otros-deportes\\\/#listItem\",\"name\":\"Otros Deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\",\"name\":\"redeportivamx.com\",\"description\":\"\\u00a1Conectando tu pasi\\u00f3n!\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/\",\"name\":\"Ivan Emeterio Araujo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa60642a347d5468bebaa7a8b887fbc0636bcc6af75b03cecafc68c651d71b42?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ivan Emeterio Araujo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#webpage\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/\",\"name\":\"\\u00a1El World Padel Tour M\\u00e9xico ya tiene a sus campeones! - Redeportiva MX\",\"description\":\"Concluy\\u00f3 el M\\u00e9xico Open 1000, celebrado en el Gimnasio Ol\\u00edmpico Juan de la Barrera y ya conocemos a los ganadores del torneo. Se celebraron los partidos finales del WPT M\\u00e9xico 1000, partidos con los que concluy\\u00f3 tambi\\u00e9n el evento. Bea Gonz\\u00e1lez y Delfina Brea vencieron a Tamara Icardo y Virginia Riera en dos sets con\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Screenshot_20231126_211156_Instagram-scaled.jpg\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#mainImage\",\"width\":2560,\"height\":1920,\"caption\":\"Foto: Instagram @wptmexico\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/11\\\/27\\\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\\\/#mainImage\"},\"datePublished\":\"2023-11-27T03:13:57+00:00\",\"dateModified\":\"2023-11-27T03:27:12+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#website\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/\",\"name\":\"redeportivamx.com\",\"description\":\"\\u00a1Conectando tu pasi\\u00f3n!\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones! - Redeportiva MX","description":"Concluy\u00f3 el M\u00e9xico Open 1000, celebrado en el Gimnasio Ol\u00edmpico Juan de la Barrera y ya conocemos a los ganadores del torneo. Se celebraron los partidos finales del WPT M\u00e9xico 1000, partidos con los que concluy\u00f3 tambi\u00e9n el evento. Bea Gonz\u00e1lez y Delfina Brea vencieron a Tamara Icardo y Virginia Riera en dos sets con","canonical_url":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#blogposting","name":"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones! - Redeportiva MX","headline":"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones!","author":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author"},"publisher":{"@id":"https:\/\/redeportivamx.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/11\/Screenshot_20231126_211156_Instagram-scaled.jpg","width":2560,"height":1920,"caption":"Foto: Instagram @wptmexico"},"datePublished":"2023-11-27T03:13:57+00:00","dateModified":"2023-11-27T03:27:12+00:00","inLanguage":"es-MX","mainEntityOfPage":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#webpage"},"isPartOf":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#webpage"},"articleSection":"Otros Deportes, Agust\u00edn Tapia, Arturo Coello, Padel, World Padel Tour"},{"@type":"BreadcrumbList","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/redeportivamx.com#listItem","position":1,"name":"Home","item":"https:\/\/redeportivamx.com","nextItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/otros-deportes\/#listItem","name":"Otros Deportes"}},{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/otros-deportes\/#listItem","position":2,"name":"Otros Deportes","item":"https:\/\/redeportivamx.com\/index.php\/category\/otros-deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#listItem","name":"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#listItem","position":3,"name":"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones!","previousItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/otros-deportes\/#listItem","name":"Otros Deportes"}}]},{"@type":"Organization","@id":"https:\/\/redeportivamx.com\/#organization","name":"redeportivamx.com","description":"\u00a1Conectando tu pasi\u00f3n!","url":"https:\/\/redeportivamx.com\/"},{"@type":"Person","@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author","url":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/","name":"Ivan Emeterio Araujo","image":{"@type":"ImageObject","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fa60642a347d5468bebaa7a8b887fbc0636bcc6af75b03cecafc68c651d71b42?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ivan Emeterio Araujo"}},{"@type":"WebPage","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#webpage","url":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/","name":"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones! - Redeportiva MX","description":"Concluy\u00f3 el M\u00e9xico Open 1000, celebrado en el Gimnasio Ol\u00edmpico Juan de la Barrera y ya conocemos a los ganadores del torneo. Se celebraron los partidos finales del WPT M\u00e9xico 1000, partidos con los que concluy\u00f3 tambi\u00e9n el evento. Bea Gonz\u00e1lez y Delfina Brea vencieron a Tamara Icardo y Virginia Riera en dos sets con","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/redeportivamx.com\/#website"},"breadcrumb":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#breadcrumblist"},"author":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author"},"creator":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/11\/Screenshot_20231126_211156_Instagram-scaled.jpg","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#mainImage","width":2560,"height":1920,"caption":"Foto: Instagram @wptmexico"},"primaryImageOfPage":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/#mainImage"},"datePublished":"2023-11-27T03:13:57+00:00","dateModified":"2023-11-27T03:27:12+00:00"},{"@type":"WebSite","@id":"https:\/\/redeportivamx.com\/#website","url":"https:\/\/redeportivamx.com\/","name":"redeportivamx.com","description":"\u00a1Conectando tu pasi\u00f3n!","inLanguage":"es-MX","publisher":{"@id":"https:\/\/redeportivamx.com\/#organization"}}]},"og:locale":"es_MX","og:site_name":"Redeportiva MX - \u00a1Conectando tu pasi\u00f3n!","og:type":"article","og:title":"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones! - Redeportiva MX","og:description":"Concluy\u00f3 el M\u00e9xico Open 1000, celebrado en el Gimnasio Ol\u00edmpico Juan de la Barrera y ya conocemos a los ganadores del torneo. Se celebraron los partidos finales del WPT M\u00e9xico 1000, partidos con los que concluy\u00f3 tambi\u00e9n el evento. Bea Gonz\u00e1lez y Delfina Brea vencieron a Tamara Icardo y Virginia Riera en dos sets con","og:url":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/","article:published_time":"2023-11-27T03:13:57+00:00","article:modified_time":"2023-11-27T03:27:12+00:00","twitter:card":"summary_large_image","twitter:title":"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones! - Redeportiva MX","twitter:description":"Concluy\u00f3 el M\u00e9xico Open 1000, celebrado en el Gimnasio Ol\u00edmpico Juan de la Barrera y ya conocemos a los ganadores del torneo. Se celebraron los partidos finales del WPT M\u00e9xico 1000, partidos con los que concluy\u00f3 tambi\u00e9n el evento. Bea Gonz\u00e1lez y Delfina Brea vencieron a Tamara Icardo y Virginia Riera en dos sets con"},"aioseo_meta_data":{"post_id":"31812","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-11-27 03:13:59","updated":"2025-06-04 15:12:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/redeportivamx.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/redeportivamx.com\/index.php\/category\/otros-deportes\/\" title=\"Otros Deportes\">Otros Deportes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/redeportivamx.com"},{"label":"Otros Deportes","link":"https:\/\/redeportivamx.com\/index.php\/category\/otros-deportes\/"},{"label":"\u00a1El World Padel Tour M\u00e9xico ya tiene a sus campeones!","link":"https:\/\/redeportivamx.com\/index.php\/2023\/11\/27\/el-world-padel-tour-mexico-ya-tiene-a-sus-campeones\/"}],"jetpack_featured_media_url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/11\/Screenshot_20231126_211156_Instagram-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/31812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/comments?post=31812"}],"version-history":[{"count":2,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/31812\/revisions"}],"predecessor-version":[{"id":31820,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/31812\/revisions\/31820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/media\/31816"}],"wp:attachment":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/media?parent=31812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/categories?post=31812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/tags?post=31812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}