{"id":28331,"date":"2023-09-28T10:15:12","date_gmt":"2023-09-28T10:15:12","guid":{"rendered":"https:\/\/redeportivamx.com\/?p=28331"},"modified":"2023-09-28T10:15:14","modified_gmt":"2023-09-28T10:15:14","slug":"crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria","status":"publish","type":"post","link":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/","title":{"rendered":"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las \u00faltima victoria de Guadalajara fue en la Jornada 5 cuando vencieron a Tijuana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ha pasado m\u00e1s de un mes desde que el Reba\u00f1o obtuvo su \u00faltima victoria, tras vencer al Xolaje cayeron en un bache del cual no han podido salir he incluso se han hundido m\u00e1s con esa derrota 4-0 en el Cl\u00e1sico Nacional. Quien pintaba para ser la estrella del equipo, Alexid Vega, contin\u00faa sin aparecer en momentos importantes y cabe resaltar nunca ha anotado o asistido cuando juega contra Am\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situaci\u00f3n empeor\u00f3 tras la m\u00e1s recien derrota, pues cayeron 1-3 en Akron ante Mazatlan qienes llegaban como lugar 16 de la tabla. Ante la reci situaci\u00f3n, Paunovic declaro: &#8220;Aceptamos la culpa, es un golpe duro, pero aqu\u00ed estamos para dar la cara. Acepto toda la\u00a0responsabilidad\u00a0y seguir\u00e9 mirando siempre en busca la mejor\u00eda&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"592\" src=\"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062867-1024x592.jpg\" alt=\"\" class=\"wp-image-28344\" srcset=\"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062867-1024x592.jpg 1024w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062867-300x173.jpg 300w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062867-768x444.jpg 768w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062867-1536x888.jpg 1536w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062867-2048x1184.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Adicion, mencion\u00f3 que el cansancio fue factor contra el equipo de Sinaloa: &#8220;Hoy hubo un factor, el&nbsp;cansancio, aparte de que el rival se prepar\u00f3 muy bien. Nos cost\u00f3 mucho, no tuvimos frescura y cometimos errores que el&nbsp;Mazatl\u00e1n&nbsp;aprovech\u00f3; no defendimos bien y se cre\u00f3 una tendencia negativa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambien pidi\u00f3 convertir el dolor en combustible: &#8220;Quiero ver ahora que la gente tenga rabia, que demuestre, que de el paso adelante por Chivas, por este equipo y por lo que somos. Para dar ese paso esnecesario que venga desde dentro, unotiene que sentir la derrota y el dolor y convertirlo en combustible, pero eso setiene que manifestar con acciones y vamos a buscar esas acciones&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este domingo el Guadalajara visitar\u00e1 a Toluca en el Nemesio Diez, \u00bfqu\u00e9 tanto est\u00e1n dispuestos a aguantar a su DT tras los malos resultados. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"636\" src=\"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062868-1024x636.jpg\" alt=\"\" class=\"wp-image-28345\" srcset=\"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062868-1024x636.jpg 1024w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062868-300x186.jpg 300w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062868-768x477.jpg 768w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/1000062868.jpg 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Las \u00faltima victoria de Guadalajara fue en la Jornada 5 cuando vencieron a Tijuana. Ha pasado m\u00e1s de un mes desde que el Reba\u00f1o obtuvo su \u00faltima victoria, tras vencer al Xolaje cayeron en un bache del cual no han podido salir he incluso se han hundido m\u00e1s con esa derrota 4-0 en el Cl\u00e1sico [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":28343,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[125,20],"class_list":["post-28331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-liga-bbva-mx","tag-chivas","tag-ligamx"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las \u00faltima victoria de Guadalajara fue en la Jornada 5 cuando vencieron a Tijuana. Ha pasado m\u00e1s de un mes desde que el Reba\u00f1o obtuvo su \u00faltima victoria, tras vencer al Xolaje cayeron en un bache del cual no han podido salir he incluso se han hundido m\u00e1s con esa derrota 4-0 en el Cl\u00e1sico\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ivan Emeterio Araujo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Redeportiva MX - \u00a1Conectando tu pasi\u00f3n!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria - Redeportiva MX\" \/>\n\t\t<meta property=\"og:description\" content=\"Las \u00faltima victoria de Guadalajara fue en la Jornada 5 cuando vencieron a Tijuana. Ha pasado m\u00e1s de un mes desde que el Reba\u00f1o obtuvo su \u00faltima victoria, tras vencer al Xolaje cayeron en un bache del cual no han podido salir he incluso se han hundido m\u00e1s con esa derrota 4-0 en el Cl\u00e1sico\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-09-28T10:15:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-09-28T10:15:14+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria - Redeportiva MX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las \u00faltima victoria de Guadalajara fue en la Jornada 5 cuando vencieron a Tijuana. Ha pasado m\u00e1s de un mes desde que el Reba\u00f1o obtuvo su \u00faltima victoria, tras vencer al Xolaje cayeron en un bache del cual no han podido salir he incluso se han hundido m\u00e1s con esa derrota 4-0 en el Cl\u00e1sico\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#blogposting\",\"name\":\"\\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria - Redeportiva MX\",\"headline\":\"\\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria\",\"author\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/20230928_041038-scaled.jpg\",\"width\":2560,\"height\":1235,\"caption\":\"_autotone\"},\"datePublished\":\"2023-09-28T10:15:12+00:00\",\"dateModified\":\"2023-09-28T10:15:14+00:00\",\"inLanguage\":\"es-MX\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#webpage\"},\"articleSection\":\"Liga BBVA MX, chivas, LigaMX\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/redeportivamx.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/liga-bbva-mx\\\/#listItem\",\"name\":\"Liga BBVA MX\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/liga-bbva-mx\\\/#listItem\",\"position\":2,\"name\":\"Liga BBVA MX\",\"item\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/liga-bbva-mx\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#listItem\",\"name\":\"\\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/liga-bbva-mx\\\/#listItem\",\"name\":\"Liga BBVA MX\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\",\"name\":\"redeportivamx.com\",\"description\":\"\\u00a1Conectando tu pasi\\u00f3n!\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/\",\"name\":\"Ivan Emeterio Araujo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa60642a347d5468bebaa7a8b887fbc0636bcc6af75b03cecafc68c651d71b42?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ivan Emeterio Araujo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#webpage\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/\",\"name\":\"\\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria - Redeportiva MX\",\"description\":\"Las \\u00faltima victoria de Guadalajara fue en la Jornada 5 cuando vencieron a Tijuana. Ha pasado m\\u00e1s de un mes desde que el Reba\\u00f1o obtuvo su \\u00faltima victoria, tras vencer al Xolaje cayeron en un bache del cual no han podido salir he incluso se han hundido m\\u00e1s con esa derrota 4-0 en el Cl\\u00e1sico\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/20230928_041038-scaled.jpg\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#mainImage\",\"width\":2560,\"height\":1235,\"caption\":\"_autotone\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/28\\\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\\\/#mainImage\"},\"datePublished\":\"2023-09-28T10:15:12+00:00\",\"dateModified\":\"2023-09-28T10:15:14+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#website\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/\",\"name\":\"redeportivamx.com\",\"description\":\"\\u00a1Conectando tu pasi\\u00f3n!\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria - Redeportiva MX","description":"Las \u00faltima victoria de Guadalajara fue en la Jornada 5 cuando vencieron a Tijuana. Ha pasado m\u00e1s de un mes desde que el Reba\u00f1o obtuvo su \u00faltima victoria, tras vencer al Xolaje cayeron en un bache del cual no han podido salir he incluso se han hundido m\u00e1s con esa derrota 4-0 en el Cl\u00e1sico","canonical_url":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#blogposting","name":"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria - Redeportiva MX","headline":"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria","author":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author"},"publisher":{"@id":"https:\/\/redeportivamx.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/20230928_041038-scaled.jpg","width":2560,"height":1235,"caption":"_autotone"},"datePublished":"2023-09-28T10:15:12+00:00","dateModified":"2023-09-28T10:15:14+00:00","inLanguage":"es-MX","mainEntityOfPage":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#webpage"},"isPartOf":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#webpage"},"articleSection":"Liga BBVA MX, chivas, LigaMX"},{"@type":"BreadcrumbList","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/redeportivamx.com#listItem","position":1,"name":"Home","item":"https:\/\/redeportivamx.com","nextItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/#listItem","name":"Liga BBVA MX"}},{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/#listItem","position":2,"name":"Liga BBVA MX","item":"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/","nextItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#listItem","name":"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria"},"previousItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#listItem","position":3,"name":"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria","previousItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/#listItem","name":"Liga BBVA MX"}}]},{"@type":"Organization","@id":"https:\/\/redeportivamx.com\/#organization","name":"redeportivamx.com","description":"\u00a1Conectando tu pasi\u00f3n!","url":"https:\/\/redeportivamx.com\/"},{"@type":"Person","@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author","url":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/","name":"Ivan Emeterio Araujo","image":{"@type":"ImageObject","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fa60642a347d5468bebaa7a8b887fbc0636bcc6af75b03cecafc68c651d71b42?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ivan Emeterio Araujo"}},{"@type":"WebPage","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#webpage","url":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/","name":"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria - Redeportiva MX","description":"Las \u00faltima victoria de Guadalajara fue en la Jornada 5 cuando vencieron a Tijuana. Ha pasado m\u00e1s de un mes desde que el Reba\u00f1o obtuvo su \u00faltima victoria, tras vencer al Xolaje cayeron en un bache del cual no han podido salir he incluso se han hundido m\u00e1s con esa derrota 4-0 en el Cl\u00e1sico","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/redeportivamx.com\/#website"},"breadcrumb":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#breadcrumblist"},"author":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author"},"creator":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/20230928_041038-scaled.jpg","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#mainImage","width":2560,"height":1235,"caption":"_autotone"},"primaryImageOfPage":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/#mainImage"},"datePublished":"2023-09-28T10:15:12+00:00","dateModified":"2023-09-28T10:15:14+00:00"},{"@type":"WebSite","@id":"https:\/\/redeportivamx.com\/#website","url":"https:\/\/redeportivamx.com\/","name":"redeportivamx.com","description":"\u00a1Conectando tu pasi\u00f3n!","inLanguage":"es-MX","publisher":{"@id":"https:\/\/redeportivamx.com\/#organization"}}]},"og:locale":"es_MX","og:site_name":"Redeportiva MX - \u00a1Conectando tu pasi\u00f3n!","og:type":"article","og:title":"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria - Redeportiva MX","og:description":"Las \u00faltima victoria de Guadalajara fue en la Jornada 5 cuando vencieron a Tijuana. Ha pasado m\u00e1s de un mes desde que el Reba\u00f1o obtuvo su \u00faltima victoria, tras vencer al Xolaje cayeron en un bache del cual no han podido salir he incluso se han hundido m\u00e1s con esa derrota 4-0 en el Cl\u00e1sico","og:url":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/","article:published_time":"2023-09-28T10:15:12+00:00","article:modified_time":"2023-09-28T10:15:14+00:00","twitter:card":"summary_large_image","twitter:title":"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria - Redeportiva MX","twitter:description":"Las \u00faltima victoria de Guadalajara fue en la Jornada 5 cuando vencieron a Tijuana. Ha pasado m\u00e1s de un mes desde que el Reba\u00f1o obtuvo su \u00faltima victoria, tras vencer al Xolaje cayeron en un bache del cual no han podido salir he incluso se han hundido m\u00e1s con esa derrota 4-0 en el Cl\u00e1sico"},"aioseo_meta_data":{"post_id":"28331","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-09-28 10:15:14","updated":"2025-06-04 14:03:34","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/redeportivamx.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/\" title=\"Liga BBVA MX\">Liga BBVA MX<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/redeportivamx.com"},{"label":"Liga BBVA MX","link":"https:\/\/redeportivamx.com\/index.php\/category\/liga-bbva-mx\/"},{"label":"\u00bfCrisis en Chivas? 5 juegos seguidos sin conocer la victoria","link":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/28\/crisis-en-chivas-5-juegos-seguidos-sin-conocer-la-victoria\/"}],"jetpack_featured_media_url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/20230928_041038-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/28331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/comments?post=28331"}],"version-history":[{"count":1,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/28331\/revisions"}],"predecessor-version":[{"id":28346,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/28331\/revisions\/28346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/media\/28343"}],"wp:attachment":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/media?parent=28331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/categories?post=28331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/tags?post=28331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}