{"id":27398,"date":"2023-09-14T21:04:07","date_gmt":"2023-09-14T21:04:07","guid":{"rendered":"https:\/\/redeportivamx.com\/?p=27398"},"modified":"2023-09-14T21:04:08","modified_gmt":"2023-09-14T21:04:08","slug":"serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje","status":"publish","type":"post","link":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/","title":{"rendered":"Serena Williams arremete contra Simona Halep por caso de dopaje"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Halep dio positivo a prueba de dopaje en el US Open 2022 y ser\u00e1 suspendida por cuatro a\u00f1os, Williams perdi\u00f3 una final en Wimbledon ante la rumana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ex-tenista profesional Serena Williams no perdi\u00f3 la oportunidad de comentar sobre la suspensi\u00f3n que enfrenta su contrincante Simona Halep, por lo que tras darse a conocer el resultado de las pruebas de la rumana, Williams public\u00f3 lo siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">8 is a better number.<\/p>&mdash; Serena Williams (@serenawilliams) <a href=\"https:\/\/twitter.com\/serenawilliams\/status\/1701646417624744344?ref_src=twsrc%5Etfw\">September 12, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><figcaption class=\"wp-element-caption\">&#8220;8 es un mejor n\u00famero&#8221;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Recordemos que en 2019, Halep derrot\u00f3 a Williams en la final de Wimbledon por lo que la estadounidense perdi\u00f3 la oportunidad de obtener su 8vo trofeo del torneo celebrado en Inglaterra. En aquella ocasi\u00f3n, Serena cay\u00f3 en dos sets, ambos siendo superada por Simona 6-2 y con lo cual la rumana obtendr\u00eda su 2do Grand Slam.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/b_halep_trophy_6809_13072019_fe-1024x682.jpg\" alt=\"\" class=\"wp-image-27400\" srcset=\"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/b_halep_trophy_6809_13072019_fe-1024x682.jpg 1024w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/b_halep_trophy_6809_13072019_fe-300x200.jpg 300w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/b_halep_trophy_6809_13072019_fe-768x512.jpg 768w, https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/b_halep_trophy_6809_13072019_fe.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Halep dio positivo a prueba de dopaje en el US Open 2022 y ser\u00e1 suspendida por cuatro a\u00f1os, Williams perdi\u00f3 una final en Wimbledon ante la rumana. La ex-tenista profesional Serena Williams no perdi\u00f3 la oportunidad de comentar sobre la suspensi\u00f3n que enfrenta su contrincante Simona Halep, por lo que tras darse a conocer el [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":27399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[234,182],"class_list":["post-27398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tenis","tag-dopaje","tag-us-open"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Halep dio positivo a prueba de dopaje en el US Open 2022 y ser\u00e1 suspendida por cuatro a\u00f1os, Williams perdi\u00f3 una final en Wimbledon ante la rumana. La ex-tenista profesional Serena Williams no perdi\u00f3 la oportunidad de comentar sobre la suspensi\u00f3n que enfrenta su contrincante Simona Halep, por lo que tras darse a conocer el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ivan Emeterio Araujo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Redeportiva MX - \u00a1Conectando tu pasi\u00f3n!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Serena Williams arremete contra Simona Halep por caso de dopaje - Redeportiva MX\" \/>\n\t\t<meta property=\"og:description\" content=\"Halep dio positivo a prueba de dopaje en el US Open 2022 y ser\u00e1 suspendida por cuatro a\u00f1os, Williams perdi\u00f3 una final en Wimbledon ante la rumana. La ex-tenista profesional Serena Williams no perdi\u00f3 la oportunidad de comentar sobre la suspensi\u00f3n que enfrenta su contrincante Simona Halep, por lo que tras darse a conocer el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-09-14T21:04:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-09-14T21:04:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Serena Williams arremete contra Simona Halep por caso de dopaje - Redeportiva MX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Halep dio positivo a prueba de dopaje en el US Open 2022 y ser\u00e1 suspendida por cuatro a\u00f1os, Williams perdi\u00f3 una final en Wimbledon ante la rumana. La ex-tenista profesional Serena Williams no perdi\u00f3 la oportunidad de comentar sobre la suspensi\u00f3n que enfrenta su contrincante Simona Halep, por lo que tras darse a conocer el\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#blogposting\",\"name\":\"Serena Williams arremete contra Simona Halep por caso de dopaje - Redeportiva MX\",\"headline\":\"Serena Williams arremete contra Simona Halep por caso de dopaje\",\"author\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/serena-williams-13852-scaled.jpg\",\"width\":2560,\"height\":1920},\"datePublished\":\"2023-09-14T21:04:07+00:00\",\"dateModified\":\"2023-09-14T21:04:08+00:00\",\"inLanguage\":\"es-MX\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#webpage\"},\"articleSection\":\"Tenis, Dopaje, US Open\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/redeportivamx.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/tenis\\\/#listItem\",\"name\":\"Tenis\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/tenis\\\/#listItem\",\"position\":2,\"name\":\"Tenis\",\"item\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/tenis\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#listItem\",\"name\":\"Serena Williams arremete contra Simona Halep por caso de dopaje\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#listItem\",\"position\":3,\"name\":\"Serena Williams arremete contra Simona Halep por caso de dopaje\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/category\\\/tenis\\\/#listItem\",\"name\":\"Tenis\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\",\"name\":\"redeportivamx.com\",\"description\":\"\\u00a1Conectando tu pasi\\u00f3n!\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/\",\"name\":\"Ivan Emeterio Araujo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fa60642a347d5468bebaa7a8b887fbc0636bcc6af75b03cecafc68c651d71b42?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ivan Emeterio Araujo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#webpage\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/\",\"name\":\"Serena Williams arremete contra Simona Halep por caso de dopaje - Redeportiva MX\",\"description\":\"Halep dio positivo a prueba de dopaje en el US Open 2022 y ser\\u00e1 suspendida por cuatro a\\u00f1os, Williams perdi\\u00f3 una final en Wimbledon ante la rumana. La ex-tenista profesional Serena Williams no perdi\\u00f3 la oportunidad de comentar sobre la suspensi\\u00f3n que enfrenta su contrincante Simona Halep, por lo que tras darse a conocer el\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/author\\\/ivan-emeterio-araujo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/serena-williams-13852-scaled.jpg\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#mainImage\",\"width\":2560,\"height\":1920},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/index.php\\\/2023\\\/09\\\/14\\\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\\\/#mainImage\"},\"datePublished\":\"2023-09-14T21:04:07+00:00\",\"dateModified\":\"2023-09-14T21:04:08+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#website\",\"url\":\"https:\\\/\\\/redeportivamx.com\\\/\",\"name\":\"redeportivamx.com\",\"description\":\"\\u00a1Conectando tu pasi\\u00f3n!\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/redeportivamx.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Serena Williams arremete contra Simona Halep por caso de dopaje - Redeportiva MX","description":"Halep dio positivo a prueba de dopaje en el US Open 2022 y ser\u00e1 suspendida por cuatro a\u00f1os, Williams perdi\u00f3 una final en Wimbledon ante la rumana. La ex-tenista profesional Serena Williams no perdi\u00f3 la oportunidad de comentar sobre la suspensi\u00f3n que enfrenta su contrincante Simona Halep, por lo que tras darse a conocer el","canonical_url":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#blogposting","name":"Serena Williams arremete contra Simona Halep por caso de dopaje - Redeportiva MX","headline":"Serena Williams arremete contra Simona Halep por caso de dopaje","author":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author"},"publisher":{"@id":"https:\/\/redeportivamx.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/serena-williams-13852-scaled.jpg","width":2560,"height":1920},"datePublished":"2023-09-14T21:04:07+00:00","dateModified":"2023-09-14T21:04:08+00:00","inLanguage":"es-MX","mainEntityOfPage":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#webpage"},"isPartOf":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#webpage"},"articleSection":"Tenis, Dopaje, US Open"},{"@type":"BreadcrumbList","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/redeportivamx.com#listItem","position":1,"name":"Home","item":"https:\/\/redeportivamx.com","nextItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/tenis\/#listItem","name":"Tenis"}},{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/tenis\/#listItem","position":2,"name":"Tenis","item":"https:\/\/redeportivamx.com\/index.php\/category\/tenis\/","nextItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#listItem","name":"Serena Williams arremete contra Simona Halep por caso de dopaje"},"previousItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#listItem","position":3,"name":"Serena Williams arremete contra Simona Halep por caso de dopaje","previousItem":{"@type":"ListItem","@id":"https:\/\/redeportivamx.com\/index.php\/category\/tenis\/#listItem","name":"Tenis"}}]},{"@type":"Organization","@id":"https:\/\/redeportivamx.com\/#organization","name":"redeportivamx.com","description":"\u00a1Conectando tu pasi\u00f3n!","url":"https:\/\/redeportivamx.com\/"},{"@type":"Person","@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author","url":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/","name":"Ivan Emeterio Araujo","image":{"@type":"ImageObject","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fa60642a347d5468bebaa7a8b887fbc0636bcc6af75b03cecafc68c651d71b42?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ivan Emeterio Araujo"}},{"@type":"WebPage","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#webpage","url":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/","name":"Serena Williams arremete contra Simona Halep por caso de dopaje - Redeportiva MX","description":"Halep dio positivo a prueba de dopaje en el US Open 2022 y ser\u00e1 suspendida por cuatro a\u00f1os, Williams perdi\u00f3 una final en Wimbledon ante la rumana. La ex-tenista profesional Serena Williams no perdi\u00f3 la oportunidad de comentar sobre la suspensi\u00f3n que enfrenta su contrincante Simona Halep, por lo que tras darse a conocer el","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/redeportivamx.com\/#website"},"breadcrumb":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#breadcrumblist"},"author":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author"},"creator":{"@id":"https:\/\/redeportivamx.com\/index.php\/author\/ivan-emeterio-araujo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/serena-williams-13852-scaled.jpg","@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#mainImage","width":2560,"height":1920},"primaryImageOfPage":{"@id":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/#mainImage"},"datePublished":"2023-09-14T21:04:07+00:00","dateModified":"2023-09-14T21:04:08+00:00"},{"@type":"WebSite","@id":"https:\/\/redeportivamx.com\/#website","url":"https:\/\/redeportivamx.com\/","name":"redeportivamx.com","description":"\u00a1Conectando tu pasi\u00f3n!","inLanguage":"es-MX","publisher":{"@id":"https:\/\/redeportivamx.com\/#organization"}}]},"og:locale":"es_MX","og:site_name":"Redeportiva MX - \u00a1Conectando tu pasi\u00f3n!","og:type":"article","og:title":"Serena Williams arremete contra Simona Halep por caso de dopaje - Redeportiva MX","og:description":"Halep dio positivo a prueba de dopaje en el US Open 2022 y ser\u00e1 suspendida por cuatro a\u00f1os, Williams perdi\u00f3 una final en Wimbledon ante la rumana. La ex-tenista profesional Serena Williams no perdi\u00f3 la oportunidad de comentar sobre la suspensi\u00f3n que enfrenta su contrincante Simona Halep, por lo que tras darse a conocer el","og:url":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/","article:published_time":"2023-09-14T21:04:07+00:00","article:modified_time":"2023-09-14T21:04:08+00:00","twitter:card":"summary_large_image","twitter:title":"Serena Williams arremete contra Simona Halep por caso de dopaje - Redeportiva MX","twitter:description":"Halep dio positivo a prueba de dopaje en el US Open 2022 y ser\u00e1 suspendida por cuatro a\u00f1os, Williams perdi\u00f3 una final en Wimbledon ante la rumana. La ex-tenista profesional Serena Williams no perdi\u00f3 la oportunidad de comentar sobre la suspensi\u00f3n que enfrenta su contrincante Simona Halep, por lo que tras darse a conocer el"},"aioseo_meta_data":{"post_id":"27398","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-09-14 21:04:08","updated":"2025-06-04 13:48:43","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/redeportivamx.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/redeportivamx.com\/index.php\/category\/tenis\/\" title=\"Tenis\">Tenis<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSerena Williams arremete contra Simona Halep por caso de dopaje\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/redeportivamx.com"},{"label":"Tenis","link":"https:\/\/redeportivamx.com\/index.php\/category\/tenis\/"},{"label":"Serena Williams arremete contra Simona Halep por caso de dopaje","link":"https:\/\/redeportivamx.com\/index.php\/2023\/09\/14\/serena-williams-arremete-contra-simona-halep-por-caso-de-dopaje\/"}],"jetpack_featured_media_url":"https:\/\/redeportivamx.com\/wp-content\/uploads\/2023\/09\/serena-williams-13852-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/27398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/comments?post=27398"}],"version-history":[{"count":1,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/27398\/revisions"}],"predecessor-version":[{"id":27401,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/posts\/27398\/revisions\/27401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/media\/27399"}],"wp:attachment":[{"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/media?parent=27398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/categories?post=27398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redeportivamx.com\/index.php\/wp-json\/wp\/v2\/tags?post=27398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}